{"id":170302,"date":"2020-09-22T13:37:21","date_gmt":"2020-09-22T11:37:21","guid":{"rendered":"https:\/\/www.hurom-europe.com\/withdrawal\/"},"modified":"2026-06-17T17:25:02","modified_gmt":"2026-06-17T15:25:02","slug":"recesso","status":"publish","type":"page","link":"https:\/\/www.hurom-europe.com\/it\/recesso\/","title":{"rendered":"Recesso"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Diritto di recesso<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hai il diritto di recedere dal presente contratto entro 14 giorni senza fornire alcuna motivazione.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il periodo di recesso scade dopo 14 giorni dal giorno in cui tu o un terzo, diverso dal vettore e da te designato, acquisisce il possesso fisico dei beni.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per esercitare il diritto di recesso, deve informarci della sua decisione di recedere dal presente contratto mediante una dichiarazione esplicita. (indirizzo e-mail: info@hurom-europe.com) A tal fine, pu\u00f2 utilizzare l\u2019apposito modulo di recesso, ma non \u00e8 obbligatorio. Per rispettare il termine di recesso, \u00e8 sufficiente inviare la notifica di esercizio del diritto di recesso prima della scadenza del periodo di recesso.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Effetti del recesso<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se recedi dal presente contratto, ti rimborseremo tutti i pagamenti che abbiamo ricevuto da te, comprese le spese di consegna (ad eccezione dei costi supplementari derivanti dalla tua eventuale scelta di un tipo di consegna diverso dal tipo meno costoso di consegna standard da noi offerto), senza indebiti ritardi e in ogni caso non oltre 14 giorni dal giorno in cui il prodotto \u00e8 arrivato presso il nostro magazzino. Il rimborso sar\u00e0 effettuato utilizzando lo stesso mezzo di pagamento da te usato per la transazione iniziale (salvo diverso accordo esplicito); in ogni caso non dovrai sostenere alcun costo quale conseguenza del rimborso. Ci riserviamo il diritto di rifiutare il rimborso fino a quando non avremo ricevuto la merce resa o fino a quando lei non avr\u00e0 fornito una prova di restituzione della merce, a seconda di quale dei due casi si verifichi prima.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dovr\u00e0 rispedire la merce o consegnarla al nostro partner logistico:&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>KS Global GmbH (Gate B)<\/strong>&nbsp;<br>Am Holzweg 28-34&nbsp;<br>65830 Kriftel, Germania&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">senza indebiti ritardi e in ogni caso entro 14 giorni dal giorno in cui ci hai comunicato il recesso dal presente contratto. Il termine \u00e8 rispettato se i beni vengono rispediti prima della scadenza del periodo di 14 giorni. Eventuali omaggi, accessori o manuali d\u2019uso forniti da Hurom Europe GmbH devono essere anch\u2019essi restituiti.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il diritto di recesso non si applica alle merci sigillate che non sono idonee al reso per motivi sanitari o igienici dopo che il sigillo \u00e8 stato rotto o rimosso.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se il valore del prodotto \u00e8 diminuito a causa di una manipolazione che \u00e8 andata oltre quanto necessario per esaminarne la natura, le caratteristiche e la funzionalit\u00e0, potremmo ridurre di conseguenza l\u2019importo del rimborso, in linea con le leggi applicabili in materia di tutela dei consumatori.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Scarica il modulo di recesso<\/h2>\n\n\n<form class=\"woocommerce-form woocommerce-form-order-withdrawal-request order-withdrawal-request\" method=\"post\">\n\t\n\t<div class=\"eu-owb-notice-wrapper\"><\/div>\n\n\t<div class=\"eu-owb-form-fields\">\n\t\t\t\t\t<div class=\"form-row form-row-first form-row-order-number\" id=\"order-withdrawal-request-order-number_field\" data-priority=\"\"><label for=\"order-withdrawal-request-order-number\" class=\"\">Order number&nbsp;<span class=\"optional\">(facoltativo)<\/span><\/label><span class=\"woocommerce-input-wrapper\"><input type=\"text\" class=\"input-text \" name=\"order_number\" id=\"order-withdrawal-request-order-number\" placeholder=\"\"  value=\"\" maxlength=\"20\" autocomplete=\"off\" \/><\/span><\/div>\n\t\t\t<div class=\"form-row form-row-last form-row-email validate-required\" id=\"order-withdrawal-request-email_field\" data-priority=\"\"><label for=\"order-withdrawal-request-email\" class=\"required_field\">Email&nbsp;<span class=\"required\" aria-hidden=\"true\">*<\/span><\/label><span class=\"woocommerce-input-wrapper\"><input type=\"text\" class=\"input-text \" name=\"email\" id=\"order-withdrawal-request-email\" placeholder=\"\"  value=\"\" aria-required=\"true\" autocomplete=\"email\" \/><\/span><\/div>\n\t\t\t<div class=\"form-row form-row-full form-row-email-repeat validate-required\" id=\"order-withdrawal-request-email-repeat_field\" data-priority=\"\"><label for=\"order-withdrawal-request-email-repeat\" class=\"required_field\">Email (repeat)&nbsp;<span class=\"required\" aria-hidden=\"true\">*<\/span><\/label><span class=\"woocommerce-input-wrapper\"><input type=\"text\" class=\"input-text \" name=\"email_repeat\" id=\"order-withdrawal-request-email-repeat\" placeholder=\"\"  value=\"\" aria-required=\"true\" autocomplete=\"email\" \/><\/span><\/div>\n\t\t\t<div class=\"form-row form-row-first form-row-first-name\" id=\"order-withdrawal-request-first-name_field\" data-priority=\"\"><label for=\"order-withdrawal-request-first-name\" class=\"\">First name&nbsp;<span class=\"optional\">(facoltativo)<\/span><\/label><span class=\"woocommerce-input-wrapper\"><input type=\"text\" class=\"input-text \" name=\"first_name\" id=\"order-withdrawal-request-first-name\" placeholder=\"\"  value=\"\" maxlength=\"40\" autocomplete=\"off\" \/><\/span><\/div>\n\t\t\t<div class=\"form-row form-row-last form-row-last-name\" id=\"order-withdrawal-request-last-name_field\" data-priority=\"\"><label for=\"order-withdrawal-request-last-name\" class=\"\">Last name&nbsp;<span class=\"optional\">(facoltativo)<\/span><\/label><span class=\"woocommerce-input-wrapper\"><input type=\"text\" class=\"input-text \" name=\"last_name\" id=\"order-withdrawal-request-last-name\" placeholder=\"\"  value=\"\" maxlength=\"40\" autocomplete=\"off\" \/><\/span><\/div>\n\t\t\t<div class=\"clear\"><\/div>\n\n\t\t\t\t\t\t\t<div class=\"order-supports-partial-withdrawal hidden\">\n\t\t\t\t\t<div class=\"form-row form-row-full form-row-manually-select-items\" id=\"manually-select-items_field\" data-priority=\"\"><span class=\"woocommerce-input-wrapper\"><label class=\"checkbox \" ><input type=\"checkbox\" name=\"manually_select_items\" id=\"manually-select-items\" value=\"1\" class=\"input-checkbox \"  \/> I want to select the items to cancel manually.&nbsp;<span class=\"optional\">(facoltativo)<\/span><\/label><\/span><\/div>\n\t\t\t\t\t<span class=\"notice eu-owb-woocommerce-select-certain-items-desc\">You will receive an email confirming receipt of your withdrawal request. In the email, you will find a link that allows you to select the items you wish to return.<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\n\t\t\t<div class=\"form-row form-row-submit\" id=\"order-withdrawal-request-submit\">\n\t\t\t<input type=\"hidden\" id=\"_wpnonce\" name=\"_wpnonce\" value=\"f68863cf34\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/it\/wp-json\/wp\/v2\/pages\/170302\" \/>\t\t\t<button type=\"submit\" class=\"woocommerce-button button woocommerce-form-return_request__submit\" name=\"order_withdrawal_request\" value=\"Confirm withdrawal\">Confirm withdrawal<\/button>\n\t\t<\/div>\n\t\n\t<div class=\"clear\"><\/div>\n\t<\/form>\n\n\n\n\n<p class=\"wp-block-paragraph\">Per qualsiasi altra domanda, visita la nostra <a href=\"https:\/\/www.hurom-europe.com\/it\/faq\/istruzioni-per-luso\/\">pagina FAQ<\/a> o contattaci <a href=\"https:\/\/www.hurom-europe.com\/it\/contattaci\/\">qui.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diritto di recesso Hai il diritto di recedere dal presente contratto entro 14 giorni senza fornire alcuna motivazione.&nbsp; Il periodo di recesso scade dopo 14 giorni dal giorno in cui tu o un terzo, diverso dal vettore e da te designato, acquisisce il possesso fisico dei beni.&nbsp; Per esercitare il diritto di recesso, deve informarci [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"templates\/template--withdrawal.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-170302","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Recesso - Hurom Europe<\/title>\n<meta name=\"description\" content=\"Qui trovi le informazioni sui tuoi diritti di recesso da un contratto stipulato con Hurom.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hurom-europe.com\/it\/recesso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recesso - Hurom Europe\" \/>\n<meta property=\"og:description\" content=\"Qui trovi le informazioni sui tuoi diritti di recesso da un contratto stipulato con Hurom.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hurom-europe.com\/it\/recesso\/\" \/>\n<meta property=\"og:site_name\" content=\"Hurom Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-17T15:25:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hurom-europe.com\/it\/recesso\/\",\"url\":\"https:\/\/www.hurom-europe.com\/it\/recesso\/\",\"name\":\"Recesso - Hurom Europe\",\"isPartOf\":{\"@id\":\"https:\/\/www.hurom-europe.com\/fr\/#website\"},\"datePublished\":\"2020-09-22T11:37:21+00:00\",\"dateModified\":\"2026-06-17T15:25:02+00:00\",\"description\":\"Qui trovi le informazioni sui tuoi diritti di recesso da un contratto stipulato con Hurom.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hurom-europe.com\/it\/recesso\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hurom-europe.com\/it\/recesso\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hurom-europe.com\/it\/recesso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.hurom-europe.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recesso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hurom-europe.com\/fr\/#website\",\"url\":\"https:\/\/www.hurom-europe.com\/fr\/\",\"name\":\"Hurom Europe\",\"description\":\"Healthy Way of Life with Slow Juicers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hurom-europe.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recesso - Hurom Europe","description":"Qui trovi le informazioni sui tuoi diritti di recesso da un contratto stipulato con Hurom.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hurom-europe.com\/it\/recesso\/","og_locale":"it_IT","og_type":"article","og_title":"Recesso - Hurom Europe","og_description":"Qui trovi le informazioni sui tuoi diritti di recesso da un contratto stipulato con Hurom.","og_url":"https:\/\/www.hurom-europe.com\/it\/recesso\/","og_site_name":"Hurom Europe","article_modified_time":"2026-06-17T15:25:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hurom-europe.com\/it\/recesso\/","url":"https:\/\/www.hurom-europe.com\/it\/recesso\/","name":"Recesso - Hurom Europe","isPartOf":{"@id":"https:\/\/www.hurom-europe.com\/fr\/#website"},"datePublished":"2020-09-22T11:37:21+00:00","dateModified":"2026-06-17T15:25:02+00:00","description":"Qui trovi le informazioni sui tuoi diritti di recesso da un contratto stipulato con Hurom.","breadcrumb":{"@id":"https:\/\/www.hurom-europe.com\/it\/recesso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hurom-europe.com\/it\/recesso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hurom-europe.com\/it\/recesso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hurom-europe.com\/it\/"},{"@type":"ListItem","position":2,"name":"Recesso"}]},{"@type":"WebSite","@id":"https:\/\/www.hurom-europe.com\/fr\/#website","url":"https:\/\/www.hurom-europe.com\/fr\/","name":"Hurom Europe","description":"Healthy Way of Life with Slow Juicers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hurom-europe.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.hurom-europe.com\/it\/wp-json\/wp\/v2\/pages\/170302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hurom-europe.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hurom-europe.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hurom-europe.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hurom-europe.com\/it\/wp-json\/wp\/v2\/comments?post=170302"}],"version-history":[{"count":0,"href":"https:\/\/www.hurom-europe.com\/it\/wp-json\/wp\/v2\/pages\/170302\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hurom-europe.com\/it\/wp-json\/wp\/v2\/media?parent=170302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}